{"id":3040,"date":"2021-03-03T08:11:30","date_gmt":"2021-03-03T08:11:30","guid":{"rendered":"https:\/\/www.ccisgon.ma\/?p=3040"},"modified":"2021-03-03T12:25:55","modified_gmt":"2021-03-03T12:25:55","slug":"%d8%ba%d8%b1%d9%81%d8%a9-%d8%a7%d9%84%d8%aa%d8%ac%d8%a7%d8%b1%d8%a9-%d9%88%d8%a7%d9%84%d8%b5%d9%86%d8%a7%d8%b9%d8%a9-%d9%88%d8%a7%d9%84%d8%ae%d8%af%d9%85%d8%a7%d8%aa-%d9%84%d8%ac%d9%87%d8%a9-%d9%83","status":"publish","type":"post","link":"https:\/\/ccisgon.servermdz.com\/fr\/%d8%ba%d8%b1%d9%81%d8%a9-%d8%a7%d9%84%d8%aa%d8%ac%d8%a7%d8%b1%d8%a9-%d9%88%d8%a7%d9%84%d8%b5%d9%86%d8%a7%d8%b9%d8%a9-%d9%88%d8%a7%d9%84%d8%ae%d8%af%d9%85%d8%a7%d8%aa-%d9%84%d8%ac%d9%87%d8%a9-%d9%83\/","title":{"rendered":"La Chambre de Commerce, d\u2019Industrie et de Services Guelmim Oued Noun tient sa session ordinaire d\u2019avril \u00e0 la commune  de Lakhssas"},"content":{"rendered":"<p style=\"font-weight: 400; text-align: justify;\">L\u2019Assembl\u00e9e g\u00e9n\u00e9rale de la Chambre de commerce, d\u2019industrie et de services Guelmim Oued Noun a tenu sa session ordinaire d\u2019avril, le mardi 23 f\u00e9vrier 2021 \u00e0 Dar al-Hay, situ\u00e9 dans la commune de Lakhssas, en pr\u00e9sence de M. le Pr\u00e9sident la commune de Lakhssas, M. Pacha Lakhssas et M. D\u00e9l\u00e9gu\u00e9 r\u00e9gional au commerce et \u00e0 l\u2019industrie \u00e0 Tiznit, ainsi que de la pr\u00e9sence de repr\u00e9sentants des autorit\u00e9s locales, des services ext\u00e9rieurs, de la soci\u00e9t\u00e9 civile, des journalistes, des m\u00e9dias et des cadres de la Chambre. Elle a pris soin de respecter les directives et pr\u00e9cautions impos\u00e9es par la pand\u00e9mie actuelle, telles que la ventilation et la d\u00e9sinfection des espaces et le port des bavettes.<\/p>\n<p style=\"text-align: justify;\">Lahoucine Aliouia, Pr\u00e9sident de la Chambre de Commerce, d\u2019Industrie et de Services de Guelmim Oued Noun, a commenc\u00e9 son discours en remerciant les participants, expliquant pourquoi la chambre a choisi de tenir sa session ordinaire \u00e0 la commune de Lakhssas, et ce, afin de se rapprocher des ressortissants de la Chambre et d&rsquo;identifier leurs probl\u00e8mes et de leur pr\u00e9senter les attributions de la Chambre.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Dans son discours, M. le Pr\u00e9sident a \u00e9galement pris note des mesures prises par le gouvernement en mati\u00e8re de couverture sociale et de retraite des commer\u00e7ants et des professionnels, qui auront des effets positifs sur l\u2019am\u00e9lioration des conditions de vie des citoyens, le soutien de leur pouvoir d\u2019achat, le maintien de leur dignit\u00e9, l\u2019immunisation des groupes vuln\u00e9rables et la r\u00e9alisation de la justice sociale, en particulier en p\u00e9riode de crise \u00e9conomique, de risques sanitaires et de diverses situations d\u2019urgence.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Il a \u00e9galement exprim\u00e9 au nom de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale de la Chambre, son hommage aux victoires diplomatiques du royaume sur la question nationale et regrettait le faible niveau, et immoral des m\u00e9dias alg\u00e9riens face \u00e0 la personne du roi, qui est respect\u00e9e et appr\u00e9ci\u00e9e \u00e0 l\u2019int\u00e9rieur et \u00e0 l\u2019ext\u00e9rieur du Maroc.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">A cette occasion, il a appel\u00e9 les personnalit\u00e9s sages d&rsquo;Alg\u00e9rie travaillants dans le domaine des m\u00e9dias \u00e0 condamner ce comportement dissoluble \u00e9mis par la cha\u00eene concern\u00e9e, \u00e0 invoquer l\u2019\u00e9thique de la profession journalistique et \u00e0 respecter les normes minimales de la profession dans le traitement des affaires marocaines, notamment avec l\u2019institution royale, que les Marocains consid\u00e8rent comme une ligne rouge et que les Marocains ne permettront pas de franchir.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Dans son discours, il a \u00e9galement soulign\u00e9 la continuit\u00e9 \u00e0 la d\u00e9fense de l\u2019unit\u00e9 du Royaume et le soutien de toutes ses institutions, dirig\u00e9es par l\u2019Institution royale dans sa sainte bataille pour pr\u00e9server l\u2019int\u00e9grit\u00e9 territoriale.<\/p>\n<div id='gallery-1' class='gallery galleryid-3040 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0097-1-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0097-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0097-1-scaled.jpg 2560w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0097-1-300x200.jpg 300w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0097-1-1024x683.jpg 1024w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0097-1-768x512.jpg 768w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0097-1-1536x1025.jpg 1536w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0097-1-2048x1367.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0104-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0104-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0104-scaled.jpg 2560w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0104-300x200.jpg 300w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0104-1024x683.jpg 1024w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0104-768x512.jpg 768w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0104-1536x1025.jpg 1536w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0104-2048x1367.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0118-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0118-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0118-scaled.jpg 2560w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0118-300x200.jpg 300w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0118-1024x683.jpg 1024w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0118-768x512.jpg 768w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0118-1536x1025.jpg 1536w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0118-2048x1367.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0163-1-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0163-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0163-1-scaled.jpg 2560w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0163-1-300x200.jpg 300w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0163-1-1024x683.jpg 1024w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0163-1-768x512.jpg 768w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0163-1-1536x1025.jpg 1536w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0163-1-2048x1367.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0229-1-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0229-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0229-1-scaled.jpg 2560w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0229-1-300x200.jpg 300w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0229-1-1024x683.jpg 1024w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0229-1-768x512.jpg 768w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0229-1-1536x1025.jpg 1536w, https:\/\/ccisgon.servermdz.com\/wp-content\/uploads\/2021\/03\/DSC_0229-1-2048x1367.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"font-weight: 400; text-align: justify;\">Pendant ladite session il a \u00e9t\u00e9 approuv\u00e9 \u00e0 l&rsquo;unanimit\u00e9 diff\u00e9rents points notamment :<\/p>\n<ol style=\"text-align: justify;\">\n<li style=\"font-weight: 400;\">Approbation du proc\u00e8s-verbal de la session d\u2019octobre \u00e0 l\u2019unanimit\u00e9 par les membres pr\u00e9sents \u00e0 la session d\u2019avril \u00e0 2021, qui s\u2019est tenue au si\u00e8ge de la commune de Lakhssas le 23 f\u00e9vrier 2021.<\/li>\n<li style=\"font-weight: 400;\">Approbation de l&rsquo;annulation l\u2019accord de partenariat inactif entre la Chambre de commerce, d\u2019industrie et de services de Guelmim Oued Noun et la Maison de l&rsquo;\u00e9lus \u00e0 Marrakech Asfi, \u00e0 l\u2019unanimit\u00e9 des \u00e9lus de la Chambre de commerce pr\u00e9sents pour l\u00e0 a session d\u2019avril 2021.<\/li>\n<li style=\"font-weight: 400;\">Approbation de l\u2019accord de partenariat entre la Chambre de commerce, d\u2019industrie et de services\u00a0 Guelmim Oued Noun , et la Fondation AttijariWafa Bank, \u00e0 l\u2019unanimit\u00e9 des membres de la Chambre \u00e9lus pr\u00e9sents \u00e0 la session d\u2019avril 2021.<\/li>\n<li>Approbation par consensus des \u00e9lus de la Chambre pr\u00e9sents \u00e0 la session d\u2019avril 2021 de nommer la grande salle de conf\u00e9rence \u00e0 Tantan, du nom de Haj Mbarek Al Battah.<\/li>\n<li style=\"font-weight: 400;\">Approbation par consensus des \u00e9lus de la Chambre pr\u00e9sents \u00e0 la session d\u2019avril 2021 de nommer la grande salle de r\u00e9union \u00e0 Tantan, du nom de la salle de r\u00e9union AlHassan Abdel Khalqi,<\/li>\n<li style=\"font-weight: 400;\">Une p\u00e9tition a \u00e9t\u00e9 adress\u00e9e \u00e0 Mr. le Wali, Guelmim Oued Noun, afin d\u2019augmenter le nombre de passagers dans les taxis de premi\u00e8re classe.<\/li>\n<li style=\"font-weight: 400;\">Une r\u00e9union a eu lieu entre la commission des affaires \u00e9conomiques et sociales de la Chambre et l\u2019Association pour la coop\u00e9ration intercommunal (Al-Amal) afin d\u2019examiner le libell\u00e9 d\u2019un accord visant \u00e0 pr\u00e9server les int\u00e9r\u00eats des propri\u00e9taires de taxis de premi\u00e8re classe sur le territoire.<\/li>\n<li style=\"font-weight: 400;\">Approbation du compte financier de la Chambre de l&rsquo;ann\u00e9e 2020, \u00e0 l\u2019unanimit\u00e9 par les membres de la Chambre pr\u00e9sents \u00e0 la session d\u2019avril 2021.<\/li>\n<li style=\"font-weight: 400;\">Approbation du projet de budget de la Chambre de 2021, \u00e0 l\u2019unanimit\u00e9 par les \u00e9lus les membres de la CCIS pr\u00e9sents \u00e0 la session d\u2019avril 2021.<\/li>\n<\/ol>\n<p style=\"font-weight: 400; text-align: justify;\">Cette session a \u00e9t\u00e9 caract\u00e9ris\u00e9 par l&rsquo;hommage rendu \u00e0 M. Lahoucine Alaouia, Pr\u00e9sident de la Chambre, par les membres de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale et de l&rsquo;association des \u0153uvres sociales de la CCIS . M. le Pr\u00e9sident, \u00e0 son tour, a adress\u00e9 un discours de remerciement et d\u2019appr\u00e9ciation \u00e0 tous ceux qui ont partag\u00e9 son cheminement de r\u00e9alisations \u00e0 la CCIS, y compris les membres, les ressortissants, les cadres de la Chambre ainsi que d\u2019autres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Assembl\u00e9e g\u00e9n\u00e9rale de la Chambre de commerce, d\u2019industrie et de services Guelmim Oued Noun a tenu sa session ordinaire d\u2019avril, le mardi 23 f\u00e9vrier 2021 \u00e0 Dar al-Hay, situ\u00e9 dans la commune de Lakhssas, en pr\u00e9sence de M. le Pr\u00e9sident la commune de Lakhssas, M. Pacha Lakhssas et M. D\u00e9l\u00e9gu\u00e9 r\u00e9gional au commerce et \u00e0 &hellip;<\/p>\n","protected":false},"author":1,"featured_media":3042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activite-de-la-ccisgon"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["ar","fr","en","es"],"languages":{"ar":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ccisgon.servermdz.com\/fr\/wp-json\/wp\/v2\/posts\/3040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccisgon.servermdz.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccisgon.servermdz.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccisgon.servermdz.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ccisgon.servermdz.com\/fr\/wp-json\/wp\/v2\/comments?post=3040"}],"version-history":[{"count":16,"href":"https:\/\/ccisgon.servermdz.com\/fr\/wp-json\/wp\/v2\/posts\/3040\/revisions"}],"predecessor-version":[{"id":3063,"href":"https:\/\/ccisgon.servermdz.com\/fr\/wp-json\/wp\/v2\/posts\/3040\/revisions\/3063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccisgon.servermdz.com\/fr\/wp-json\/wp\/v2\/media\/3042"}],"wp:attachment":[{"href":"https:\/\/ccisgon.servermdz.com\/fr\/wp-json\/wp\/v2\/media?parent=3040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccisgon.servermdz.com\/fr\/wp-json\/wp\/v2\/categories?post=3040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccisgon.servermdz.com\/fr\/wp-json\/wp\/v2\/tags?post=3040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}